{"id":1407,"date":"2023-11-06T13:43:22","date_gmt":"2023-11-06T12:43:22","guid":{"rendered":"https:\/\/innova.campogalego.gal\/?p=1407"},"modified":"2023-11-06T14:39:46","modified_gmt":"2023-11-06T13:39:46","slug":"masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario","status":"publish","type":"post","link":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html","title":{"rendered":"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.clusteralimentariodegalicia.org\/\" rel=\"noopener\" target=\"_blank\"><strong>Cl\u00faster Alimentario de Galicia (Clusaga)<\/strong><\/a> presenta su primer Programa de Desarrollo Directivo para Empresas Alimentarias gallegas. El curso, que tendr\u00e1 lugar de marzo a noviembre de 2024, se inaugura el 9 de noviembre con una Masterclass titulada \u2018Perspectivas de la econom\u00eda mundial e impacto en el sector alimentario\u2019.<\/p>\n<p>La sesi\u00f3n ser\u00e1 de 12:00 a 14:00 horas en el Centro Abanca Obra Social (Plaza Cervantes, Santiago de Compostela) y ser\u00e1 impartida por el economista, director general de Consulta Abierta y exconsejero del Fondo Monetario Internacional Mario Weitz. En la charla se ofrecer\u00e1 una visi\u00f3n global de la econom\u00eda mundial y espa\u00f1ola, incidiendo en su influencia en el sector de la alimentaci\u00f3n.<\/p>\n<p>El proyecto est\u00e1 dise\u00f1ado junto a la Universidad Intercontinental de la Empresa (UIE) y es una iniciativa a favor del talento y la mejora de la competitividad del sector alimentario de Galicia, cuyo objetivo es impulsar el crecimiento y la excelencia de los profesionales que integran las empresas del mismo. nace de la idea de que, en un entorno competitivo y din\u00e1mico del sector alimentario, las empresas enfrentan desaf\u00edos constantes, desde la creciente demanda de productos innovadores y saludables, hasta las cambiantes regulaciones y tendencias de mercado. Por eso, contar con l\u00edderes altamente capacitados y orientados al \u00e9xito se convierte en una necesidad imperante para garantizar el crecimiento de las organizaciones.<\/p>\n<p><strong>Fortalecer las habilidades de liderazgo <\/strong><br \/>\nLa creaci\u00f3n de talento y la mejora de la capacitaci\u00f3n de los trabajadores del sector son unas de las medidas recogidas en el Plan Estrat\u00e9gico 2021-2025 de Clusaga. As\u00ed, el Plan de Formaci\u00f3n de la asociaci\u00f3n para 2024 consta de diversas iniciativas distribuidas en tres partes. Una de ellas es el programa mencionado, que se enmarca en la categor\u00eda de Alta Direcci\u00f3n, y cuenta de 25 sesiones de ocho horas. Su misi\u00f3n es fortalecer las habilidades directivas y de liderazgo de los profesionales del sector para fomentar la innovaci\u00f3n, la eficiencia y el \u00e9xito en sus organizaciones.<\/p>\n<p>Los principales objetivos son la mejora en la formulaci\u00f3n e implementaci\u00f3n de la estrategia corporativa, el desarrollo de una visi\u00f3n estrat\u00e9gica global orientada a resultados o el fomento de las habilidades de liderazgo para la gesti\u00f3n eficiente de equipos, entre otros.<\/p>\n<ul>\n<li><a href=\"https:\/\/forms.zohopublic.eu\/clusaga\/form\/MasterclassPresentacinProgramaDesarrolloDirectivop\/formperma\/b585og94doOlel_ggDX602I7oGYqvjOKbl0iMkeiqD8\" target=\"_blank\" rel=\"noopener\">Inscripci\u00f3n <\/a><\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" width=\"800\" height=\"1200\" class=\"aligncenter size-full wp-image-1424 lazyload\" sizes=\"(max-width:767px) 480px, (max-width:800px) 100vw, 800px\" data-src=\"https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/cluster.jpg\" data-srcset=\"https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/cluster.jpg 800w, https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/cluster-200x300.jpg 200w, https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/cluster-683x1024.jpg 683w\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cl\u00faster Alimentario de Galicia (Clusaga) presenta su primer Programa de Desarrollo Directivo para Empresas Alimentarias gallegas. El curso, que tendr\u00e1 lugar de marzo a noviembre<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":7,"featured_media":1426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[227],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego\" \/>\n<meta property=\"og:description\" content=\"El Cl\u00faster Alimentario de Galicia (Clusaga) presenta su primer Programa de Desarrollo Directivo para Empresas Alimentarias gallegas. El curso, que tendr\u00e1 lugar de marzo a noviembre [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html\" \/>\n<meta property=\"og:site_name\" content=\"Innova - Campo Galego\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-06T12:43:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T13:39:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/dieta-alimentos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"noelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html\",\"url\":\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html\",\"name\":\"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego\",\"isPartOf\":{\"@id\":\"https:\/\/innova.campogalego.gal\/es#website\"},\"datePublished\":\"2023-11-06T12:43:22+00:00\",\"dateModified\":\"2023-11-06T13:39:46+00:00\",\"author\":{\"@id\":\"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/5f73832eaae2d2d2fe19cdf56f76e921\"},\"breadcrumb\":{\"@id\":\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/innova.campogalego.gal\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/innova.campogalego.gal\/es#website\",\"url\":\"https:\/\/innova.campogalego.gal\/es\",\"name\":\"Innova - Campo Galego\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/innova.campogalego.gal\/es?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/5f73832eaae2d2d2fe19cdf56f76e921\",\"name\":\"noelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b4912756e566b19c7962f96cfebbb102?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b4912756e566b19c7962f96cfebbb102?s=96&d=mm&r=g\",\"caption\":\"noelia\"},\"url\":\"https:\/\/innova.campogalego.gal\/es\/author\/noelia\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html","og_locale":"es_ES","og_type":"article","og_title":"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego","og_description":"El Cl\u00faster Alimentario de Galicia (Clusaga) presenta su primer Programa de Desarrollo Directivo para Empresas Alimentarias gallegas. El curso, que tendr\u00e1 lugar de marzo a noviembre [\u2026]","og_url":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html","og_site_name":"Innova - Campo Galego","article_published_time":"2023-11-06T12:43:22+00:00","article_modified_time":"2023-11-06T13:39:46+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/innova.campogalego.gal\/wp-content\/uploads\/2023\/11\/dieta-alimentos.jpg","type":"image\/jpeg"}],"author":"noelia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"noelia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html","url":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html","name":"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario - Innova - Campo Galego","isPartOf":{"@id":"https:\/\/innova.campogalego.gal\/es#website"},"datePublished":"2023-11-06T12:43:22+00:00","dateModified":"2023-11-06T13:39:46+00:00","author":{"@id":"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/5f73832eaae2d2d2fe19cdf56f76e921"},"breadcrumb":{"@id":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/innova.campogalego.gal\/es\/agroalimentacion-es\/masterclass-sobre-el-impacto-de-la-economia-mundial-en-el-sector-alimentario.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/innova.campogalego.gal\/es"},{"@type":"ListItem","position":2,"name":"Masterclass sobre el impacto de la econom\u00eda mundial en el sector alimentario"}]},{"@type":"WebSite","@id":"https:\/\/innova.campogalego.gal\/es#website","url":"https:\/\/innova.campogalego.gal\/es","name":"Innova - Campo Galego","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/innova.campogalego.gal\/es?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/5f73832eaae2d2d2fe19cdf56f76e921","name":"noelia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/innova.campogalego.gal\/es#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b4912756e566b19c7962f96cfebbb102?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4912756e566b19c7962f96cfebbb102?s=96&d=mm&r=g","caption":"noelia"},"url":"https:\/\/innova.campogalego.gal\/es\/author\/noelia"}]}},"_links":{"self":[{"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/posts\/1407"}],"collection":[{"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":2,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/posts\/1407\/revisions"}],"predecessor-version":[{"id":1429,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/posts\/1407\/revisions\/1429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/media\/1426"}],"wp:attachment":[{"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/media?parent=1407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/categories?post=1407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/innova.campogalego.gal\/es\/wp-json\/wp\/v2\/tags?post=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}